{"id":10001187,"date":"2024-05-21T09:42:58","date_gmt":"2024-05-21T12:42:58","guid":{"rendered":"https:\/\/dsenb.ca\/?post_type=tribe_events&#038;p=5242"},"modified":"2024-05-21T11:49:40","modified_gmt":"2024-05-21T14:49:40","slug":"marche-des-fermiers-de-bouctouche-farmers-market-3","status":"publish","type":"tribe_events","link":"https:\/\/dsenb.ca\/fr\/event\/marche-des-fermiers-de-bouctouche-farmers-market-3\/2024-08-17\/","title":{"rendered":"March\u00e9 des fermiers de Bouctouche Farmers' Market"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"5247\" data-permalink=\"https:\/\/dsenb.ca\/fr\/event\/marche-des-fermiers-de-bouctouche-farmers-market-3\/2024-05-18\/market-bouctouche\/\" data-orig-file=\"https:\/\/i0.wp.com\/dsenb.ca\/wp-content\/uploads\/2024\/05\/market-bouctouche.jpg?fit=960%2C540&amp;ssl=1\" data-orig-size=\"960,540\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"market bouctouche\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/dsenb.ca\/wp-content\/uploads\/2024\/05\/market-bouctouche.jpg?fit=800%2C450&amp;ssl=1\" class=\"alignnone size-medium wp-image-5247\" src=\"https:\/\/i0.wp.com\/dsenb.ca\/wp-content\/uploads\/2024\/05\/market-bouctouche.jpg?resize=300%2C169&#038;ssl=1\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/i0.wp.com\/dsenb.ca\/wp-content\/uploads\/2024\/05\/market-bouctouche.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/dsenb.ca\/wp-content\/uploads\/2024\/05\/market-bouctouche.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/dsenb.ca\/wp-content\/uploads\/2024\/05\/market-bouctouche.jpg?resize=18%2C10&amp;ssl=1 18w, https:\/\/i0.wp.com\/dsenb.ca\/wp-content\/uploads\/2024\/05\/market-bouctouche.jpg?w=960&amp;ssl=1 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":220940507,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[1434],"class_list":["post-10001187","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-market","cat_market","tribe-recurring-event","tribe-recurring-event-parent"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"ginettedoiron\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/dsenb.ca\/fr\/event\/marche-des-fermiers-de-bouctouche-farmers-market-3\/2024-08-17\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_CA\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Destination Southeast - New Brunswick\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"March\u00e9 des fermiers de Bouctouche Farmers\u2019 Market - Destination Southeast\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/dsenb.ca\/fr\/event\/marche-des-fermiers-de-bouctouche-farmers-market-3\/2024-08-17\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/dsenb.ca\/wp-content\/uploads\/2022\/05\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/dsenb.ca\/wp-content\/uploads\/2022\/05\/logo.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"486\" \/>\n\t\t<meta property=\"og:image:height\" content=\"134\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-05-21T12:42:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-05-21T14:49:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"March\u00e9 des fermiers de Bouctouche Farmers\u2019 Market - Destination Southeast\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/dsenb.ca\/wp-content\/uploads\/2022\/05\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/event\\\/marche-des-fermiers-de-bouctouche-farmers-market-3\\\/2024-08-17\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dsenb.ca\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/events\\\/#listItem\",\"name\":\"\\u00c9v\\u00e8nements\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/events\\\/#listItem\",\"position\":2,\"name\":\"\\u00c9v\\u00e8nements\",\"item\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/events\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/events\\\/categorie\\\/market\\\/#listItem\",\"name\":\"Market\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/events\\\/categorie\\\/market\\\/#listItem\",\"position\":3,\"name\":\"Market\",\"item\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/events\\\/categorie\\\/market\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/event\\\/marche-des-fermiers-de-bouctouche-farmers-market-3\\\/2024-08-17\\\/#listItem\",\"name\":\"March\\u00e9 des fermiers de Bouctouche Farmers&#8217; Market\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/events\\\/#listItem\",\"name\":\"\\u00c9v\\u00e8nements\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/event\\\/marche-des-fermiers-de-bouctouche-farmers-market-3\\\/2024-08-17\\\/#listItem\",\"position\":4,\"name\":\"March\\u00e9 des fermiers de Bouctouche Farmers&#8217; Market\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/events\\\/categorie\\\/market\\\/#listItem\",\"name\":\"Market\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/#organization\",\"name\":\"Brunswick Destination\",\"description\":\"New Brunswick\",\"url\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/dsenb.ca\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo.png?fit=486%2C134&ssl=1\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/event\\\/marche-des-fermiers-de-bouctouche-farmers-market-3\\\/2024-08-17\\\/#organizationLogo\",\"width\":486,\"height\":134},\"image\":{\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/event\\\/marche-des-fermiers-de-bouctouche-farmers-market-3\\\/2024-08-17\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/author\\\/ginettedoiron\\\/#author\",\"url\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/author\\\/ginettedoiron\\\/\",\"name\":\"ginettedoiron\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/event\\\/marche-des-fermiers-de-bouctouche-farmers-market-3\\\/2024-08-17\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dcf6d4d93355e98926a2fa534481e69a15f865f5cb0d86bdf9df5b2c2f39fe37?s=96&d=identicon&r=g\",\"width\":96,\"height\":96,\"caption\":\"ginettedoiron\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/event\\\/marche-des-fermiers-de-bouctouche-farmers-market-3\\\/2024-08-17\\\/#webpage\",\"url\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/event\\\/marche-des-fermiers-de-bouctouche-farmers-market-3\\\/2024-08-17\\\/\",\"name\":\"March\\u00e9 des fermiers de Bouctouche Farmers\\u2019 Market - Destination Southeast\",\"inLanguage\":\"fr-CA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/event\\\/marche-des-fermiers-de-bouctouche-farmers-market-3\\\/2024-08-17\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/author\\\/ginettedoiron\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/author\\\/ginettedoiron\\\/#author\"},\"datePublished\":\"2024-05-21T09:42:58-03:00\",\"dateModified\":\"2024-05-21T11:49:40-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/\",\"name\":\"Destination Southeast\",\"description\":\"New Brunswick\",\"inLanguage\":\"fr-CA\",\"publisher\":{\"@id\":\"https:\\\/\\\/dsenb.ca\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"March\u00e9 des fermiers de Bouctouche Farmers\u2019 Market - Destination Southeast","description":"","canonical_url":"https:\/\/dsenb.ca\/fr\/event\/marche-des-fermiers-de-bouctouche-farmers-market-3\/2024-08-17\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/dsenb.ca\/fr\/event\/marche-des-fermiers-de-bouctouche-farmers-market-3\/2024-08-17\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/dsenb.ca\/fr#listItem","position":1,"name":"Home","item":"https:\/\/dsenb.ca\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/dsenb.ca\/fr\/events\/#listItem","name":"\u00c9v\u00e8nements"}},{"@type":"ListItem","@id":"https:\/\/dsenb.ca\/fr\/events\/#listItem","position":2,"name":"\u00c9v\u00e8nements","item":"https:\/\/dsenb.ca\/fr\/events\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dsenb.ca\/fr\/events\/categorie\/market\/#listItem","name":"Market"},"previousItem":{"@type":"ListItem","@id":"https:\/\/dsenb.ca\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/dsenb.ca\/fr\/events\/categorie\/market\/#listItem","position":3,"name":"Market","item":"https:\/\/dsenb.ca\/fr\/events\/categorie\/market\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dsenb.ca\/fr\/event\/marche-des-fermiers-de-bouctouche-farmers-market-3\/2024-08-17\/#listItem","name":"March\u00e9 des fermiers de Bouctouche Farmers&#8217; Market"},"previousItem":{"@type":"ListItem","@id":"https:\/\/dsenb.ca\/fr\/events\/#listItem","name":"\u00c9v\u00e8nements"}},{"@type":"ListItem","@id":"https:\/\/dsenb.ca\/fr\/event\/marche-des-fermiers-de-bouctouche-farmers-market-3\/2024-08-17\/#listItem","position":4,"name":"March\u00e9 des fermiers de Bouctouche Farmers&#8217; Market","previousItem":{"@type":"ListItem","@id":"https:\/\/dsenb.ca\/fr\/events\/categorie\/market\/#listItem","name":"Market"}}]},{"@type":"Organization","@id":"https:\/\/dsenb.ca\/fr\/#organization","name":"Brunswick Destination","description":"New Brunswick","url":"https:\/\/dsenb.ca\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/dsenb.ca\/wp-content\/uploads\/2022\/05\/logo.png?fit=486%2C134&ssl=1","@id":"https:\/\/dsenb.ca\/fr\/event\/marche-des-fermiers-de-bouctouche-farmers-market-3\/2024-08-17\/#organizationLogo","width":486,"height":134},"image":{"@id":"https:\/\/dsenb.ca\/fr\/event\/marche-des-fermiers-de-bouctouche-farmers-market-3\/2024-08-17\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/dsenb.ca\/fr\/author\/ginettedoiron\/#author","url":"https:\/\/dsenb.ca\/fr\/author\/ginettedoiron\/","name":"ginettedoiron","image":{"@type":"ImageObject","@id":"https:\/\/dsenb.ca\/fr\/event\/marche-des-fermiers-de-bouctouche-farmers-market-3\/2024-08-17\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/dcf6d4d93355e98926a2fa534481e69a15f865f5cb0d86bdf9df5b2c2f39fe37?s=96&d=identicon&r=g","width":96,"height":96,"caption":"ginettedoiron"}},{"@type":"WebPage","@id":"https:\/\/dsenb.ca\/fr\/event\/marche-des-fermiers-de-bouctouche-farmers-market-3\/2024-08-17\/#webpage","url":"https:\/\/dsenb.ca\/fr\/event\/marche-des-fermiers-de-bouctouche-farmers-market-3\/2024-08-17\/","name":"March\u00e9 des fermiers de Bouctouche Farmers\u2019 Market - Destination Southeast","inLanguage":"fr-CA","isPartOf":{"@id":"https:\/\/dsenb.ca\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/dsenb.ca\/fr\/event\/marche-des-fermiers-de-bouctouche-farmers-market-3\/2024-08-17\/#breadcrumblist"},"author":{"@id":"https:\/\/dsenb.ca\/fr\/author\/ginettedoiron\/#author"},"creator":{"@id":"https:\/\/dsenb.ca\/fr\/author\/ginettedoiron\/#author"},"datePublished":"2024-05-21T09:42:58-03:00","dateModified":"2024-05-21T11:49:40-03:00"},{"@type":"WebSite","@id":"https:\/\/dsenb.ca\/fr\/#website","url":"https:\/\/dsenb.ca\/fr\/","name":"Destination Southeast","description":"New Brunswick","inLanguage":"fr-CA","publisher":{"@id":"https:\/\/dsenb.ca\/fr\/#organization"}}]},"og:locale":"fr_CA","og:site_name":"Destination Southeast - New Brunswick","og:type":"article","og:title":"March\u00e9 des fermiers de Bouctouche Farmers\u2019 Market - Destination Southeast","og:url":"https:\/\/dsenb.ca\/fr\/event\/marche-des-fermiers-de-bouctouche-farmers-market-3\/2024-08-17\/","og:image":"https:\/\/dsenb.ca\/wp-content\/uploads\/2022\/05\/logo.png","og:image:secure_url":"https:\/\/dsenb.ca\/wp-content\/uploads\/2022\/05\/logo.png","og:image:width":486,"og:image:height":134,"article:published_time":"2024-05-21T12:42:58+00:00","article:modified_time":"2024-05-21T14:49:40+00:00","twitter:card":"summary_large_image","twitter:title":"March\u00e9 des fermiers de Bouctouche Farmers\u2019 Market - Destination Southeast","twitter:image":"https:\/\/dsenb.ca\/wp-content\/uploads\/2022\/05\/logo.png"},"aioseo_meta_data":[],"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/dsenb.ca\/fr\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/dsenb.ca\/fr\/events\/\" title=\"\u00c9v\u00e8nements\">\u00c9v\u00e8nements<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/dsenb.ca\/fr\/events\/categorie\/market\/\" title=\"Market\">Market<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMarch\u00e9 des fermiers de Bouctouche Farmers\u2019 Market\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/dsenb.ca\/fr"},{"label":"\u00c9v\u00e8nements","link":"https:\/\/dsenb.ca\/fr\/events\/"},{"label":"Market","link":"https:\/\/dsenb.ca\/fr\/events\/categorie\/market\/"},{"label":"March\u00e9 des fermiers de Bouctouche Farmers&#8217; Market","link":"https:\/\/dsenb.ca\/fr\/event\/marche-des-fermiers-de-bouctouche-farmers-market-3\/2024-08-17\/"}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"acf":[],"_links":{"self":[{"href":"https:\/\/dsenb.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/10001187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dsenb.ca\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/dsenb.ca\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/dsenb.ca\/fr\/wp-json\/wp\/v2\/users\/220940507"}],"version-history":[{"count":0,"href":"https:\/\/dsenb.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/10001187\/revisions"}],"wp:attachment":[{"href":"https:\/\/dsenb.ca\/fr\/wp-json\/wp\/v2\/media?parent=10001187"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dsenb.ca\/fr\/wp-json\/wp\/v2\/tags?post=10001187"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/dsenb.ca\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=10001187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}